{"id":5436,"date":"2026-02-05T07:24:17","date_gmt":"2026-02-05T07:24:17","guid":{"rendered":"https:\/\/rapidcision.com\/?page_id=5436"},"modified":"2026-06-06T13:23:30","modified_gmt":"2026-06-06T13:23:30","slug":"terms-and-conditions","status":"publish","type":"page","link":"https:\/\/rapidcision.com\/es\/terms-and-conditions\/","title":{"rendered":"Condiciones generales"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"5436\" class=\"elementor elementor-5436\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8664d86 e-flex e-con-boxed e-con e-parent\" data-id=\"8664d86\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a1d6deb elementor-widget elementor-widget-heading\" data-id=\"a1d6deb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Condiciones generales<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2f3101e elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"2f3101e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tNuestros T\u00e9rminos y Condiciones describen las normas y reglas de uso de nuestro sitio web. L\u00e9alas atentamente para conocer sus derechos y obligaciones al interactuar con nuestros servicios.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-47501b7 elementor-widget elementor-widget-button\" data-id=\"47501b7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/app.rapidcision.com\/users\/sign_in\/index.html\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Presupuesto inmediato<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3e3bbf1 e-flex e-con-boxed e-con e-parent\" data-id=\"3e3bbf1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-82c6171 elementor-widget elementor-widget-text-editor\" data-id=\"82c6171\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p data-start=\"404\" data-end=\"697\"><strong data-start=\"404\" data-end=\"420\">Introducci\u00f3n<\/strong><br data-start=\"420\" data-end=\"423\" \/>Bienvenido a Rapidcision. Al acceder o utilizar nuestro sitio web y nuestros servicios, usted acepta cumplir con estos T\u00e9rminos y Condiciones. Estos t\u00e9rminos rigen su uso del sitio web y los servicios que ofrecemos. Si no est\u00e1 de acuerdo con estos t\u00e9rminos, debe abstenerse de utilizar nuestro sitio web.<\/p><p data-start=\"699\" data-end=\"992\"><strong data-start=\"699\" data-end=\"721\">Uso del sitio web<\/strong><br data-start=\"721\" data-end=\"724\" \/>Usted se compromete a utilizar nuestro sitio web \u00fanicamente con fines l\u00edcitos y de conformidad con las presentes Condiciones. Se le proh\u00edbe utilizar el sitio de cualquier forma que pueda da\u00f1ar, inutilizar, sobrecargar o deteriorar el sitio web o interferir con el uso del sitio por parte de cualquier otro usuario.<\/p><p data-start=\"994\" data-end=\"1023\">No debe utilizar el sitio web:<\/p><ul data-start=\"1024\" data-end=\"1307\"><li data-start=\"1024\" data-end=\"1110\"><p data-start=\"1026\" data-end=\"1110\">Participar en cualquier actividad ilegal o prohibida por estas condiciones.<\/p><\/li><li data-start=\"1111\" data-end=\"1204\"><p data-start=\"1113\" data-end=\"1204\">Transmitir contenidos da\u00f1inos o ilegales, incluidos programas maliciosos, virus u otros archivos da\u00f1inos.<\/p><\/li><li data-start=\"1205\" data-end=\"1307\"><p data-start=\"1207\" data-end=\"1307\">Hacerse pasar por cualquier persona o entidad o representar falsamente su afiliaci\u00f3n con cualquier persona o entidad.<\/p><\/li><\/ul><p data-start=\"1309\" data-end=\"1658\"><strong data-start=\"1309\" data-end=\"1333\">Registro de cuentas<\/strong><br data-start=\"1333\" data-end=\"1336\" \/>Para acceder a determinadas funciones de nuestro sitio web, es posible que deba crear una cuenta. Debe proporcionar informaci\u00f3n precisa y completa al crear su cuenta y comprometerse a mantenerla actualizada. Usted es responsable de mantener la confidencialidad de las credenciales de su cuenta y de todas las actividades que se realicen en ella.<\/p><p data-start=\"1660\" data-end=\"1784\">Si cree que su cuenta se ha visto comprometida o que se ha producido un uso no autorizado, debe notific\u00e1rnoslo inmediatamente.<\/p><p data-start=\"1786\" data-end=\"2035\"><strong data-start=\"1786\" data-end=\"1807\">Servicios prestados<\/strong><br data-start=\"1807\" data-end=\"1810\" \/>Rapidcision ofrece servicios personalizados de mecanizado CNC, moldeado, fabricaci\u00f3n y prototipado r\u00e1pido, adem\u00e1s de otras soluciones de fabricaci\u00f3n. Los t\u00e9rminos descritos en este documento se aplican a todos los usuarios de nuestro sitio web y servicios.<\/p><p data-start=\"2037\" data-end=\"2147\">Nos reservamos el derecho a modificar, suspender o interrumpir cualquiera de nuestros servicios en cualquier momento, sin previo aviso.<\/p><p data-start=\"2149\" data-end=\"2425\"><strong data-start=\"2149\" data-end=\"2174\">Propiedad intelectual<\/strong><br data-start=\"2174\" data-end=\"2177\" \/>Todos los contenidos, logotipos, dise\u00f1os, marcas registradas y dem\u00e1s propiedad intelectual de la p\u00e1gina web son propiedad de Rapidcision o de sus licenciantes. Usted no puede utilizar, reproducir o distribuir cualquiera de esta propiedad intelectual sin nuestro consentimiento previo por escrito.<\/p><p data-start=\"2427\" data-end=\"2734\"><strong data-start=\"2427\" data-end=\"2450\">Precios y pagos<\/strong><br data-start=\"2450\" data-end=\"2453\" \/>Los precios de nuestros servicios figuran en el sitio web y est\u00e1n sujetos a cambios sin previo aviso. Los precios que figuran en el sitio web son meramente informativos y no constituyen una oferta. Se le facilitar\u00e1 un presupuesto definitivo tras la presentaci\u00f3n de su solicitud de servicios.<\/p><p data-start=\"2736\" data-end=\"2941\">Los pagos de los servicios deben efectuarse en el momento del pedido, y todas las transacciones se procesan de forma segura. Aceptamos varios m\u00e9todos de pago, como tarjetas de cr\u00e9dito, transferencias bancarias y otros sistemas de pago en l\u00ednea.<\/p><p data-start=\"2943\" data-end=\"3204\"><strong data-start=\"2943\" data-end=\"2978\">Cancelaci\u00f3n y reembolso de pedidos<\/strong><br data-start=\"2978\" data-end=\"2981\" \/>Una vez confirmado un pedido, no puede cancelarse ni reembolsarse a menos que el servicio no se haya prestado o si hay alg\u00fan problema con el pedido. Para cualquier duda sobre cancelaciones o reembolsos, p\u00f3ngase en contacto con nosotros directamente.<\/p><p data-start=\"3206\" data-end=\"3488\"><strong data-start=\"3206\" data-end=\"3233\">Limitaci\u00f3n de responsabilidad<\/strong><br data-start=\"3233\" data-end=\"3236\" \/>Rapidcision no ser\u00e1 responsable de ning\u00fan da\u00f1o directo, indirecto, incidental o consecuente derivado del uso o de la imposibilidad de usar nuestro sitio web o nuestros servicios. Nuestra responsabilidad se limita a la cantidad que usted pag\u00f3 por el servicio espec\u00edfico que caus\u00f3 el da\u00f1o.<\/p><p data-start=\"3490\" data-end=\"3766\"><strong data-start=\"3490\" data-end=\"3509\">Indemnizaci\u00f3n<\/strong><br data-start=\"3509\" data-end=\"3512\" \/>Usted se compromete a indemnizar y mantener indemne a Rapidcision, sus empleados, directores y afiliados de cualquier reclamaci\u00f3n, p\u00e9rdida o da\u00f1o, incluyendo honorarios legales, resultantes de su violaci\u00f3n de estos T\u00e9rminos y Condiciones o su uso de la p\u00e1gina web y los servicios.<\/p><p data-start=\"3768\" data-end=\"4074\"><strong data-start=\"3768\" data-end=\"3789\">Enlaces de terceros<\/strong><br data-start=\"3789\" data-end=\"3792\" \/>Nuestro sitio web puede contener enlaces a sitios web de terceros. Estos enlaces se facilitan \u00fanicamente para su comodidad y con fines informativos. No aprobamos ni controlamos el contenido de estos sitios web de terceros, y no somos responsables de ning\u00fan contenido, producto o servicio que puedan ofrecer.<\/p><p data-start=\"4076\" data-end=\"4297\"><strong data-start=\"4076\" data-end=\"4087\">Privacidad<\/strong><br data-start=\"4087\" data-end=\"4090\" \/>El uso de nuestro sitio web tambi\u00e9n se rige por nuestra Pol\u00edtica de privacidad, que describe c\u00f3mo recopilamos y utilizamos sus datos personales. Consulte nuestra Pol\u00edtica de privacidad para obtener m\u00e1s informaci\u00f3n sobre el tratamiento de sus datos.<\/p><p data-start=\"4299\" data-end=\"4549\"><strong data-start=\"4299\" data-end=\"4314\">Terminaci\u00f3n<\/strong><br data-start=\"4314\" data-end=\"4317\" \/>Nos reservamos el derecho a suspender o cancelar su acceso al sitio web y a los servicios si infringe estas Condiciones. En caso de rescisi\u00f3n, cesar\u00e1n todos los derechos que se le hayan concedido y deber\u00e1 dejar de utilizar inmediatamente el sitio web.<\/p><p data-start=\"4551\" data-end=\"4807\"><strong data-start=\"4551\" data-end=\"4568\">Derecho aplicable<\/strong><br data-start=\"4568\" data-end=\"4571\" \/>Estos T\u00e9rminos y Condiciones se rigen e interpretan de acuerdo con las leyes de la jurisdicci\u00f3n en la que opera Rapidcision. Cualquier disputa derivada de estos t\u00e9rminos se resolver\u00e1 en los tribunales competentes de dicha jurisdicci\u00f3n.<\/p><p data-start=\"4809\" data-end=\"5058\"><strong data-start=\"4809\" data-end=\"4835\">Modificaciones de estas condiciones<\/strong><br data-start=\"4835\" data-end=\"4838\" \/>Podemos actualizar estos T\u00e9rminos y Condiciones de vez en cuando. Cualquier cambio se publicar\u00e1 en esta p\u00e1gina con una nueva fecha de entrada en vigor. Es su responsabilidad revisar estos t\u00e9rminos peri\u00f3dicamente para mantenerse informado de cualquier cambio.<\/p><p data-start=\"5060\" data-end=\"5170\"><strong data-start=\"5060\" data-end=\"5074\">P\u00f3ngase en contacto con nosotros<\/strong><br data-start=\"5074\" data-end=\"5077\" \/>Si tiene alguna pregunta o duda sobre estas Condiciones, p\u00f3ngase en contacto con nosotros en:<\/p><p data-start=\"5172\" data-end=\"5394\"><strong data-start=\"5172\" data-end=\"5181\">Tel\u00e9fono<\/strong>: +86 0755-85276703<br data-start=\"5200\" data-end=\"5203\" \/><strong data-start=\"5203\" data-end=\"5212\">Correo electr\u00f3nico<\/strong>: <a class=\"decorated-link cursor-pointer\" rel=\"noopener\" data-start=\"5214\" data-end=\"5259\">info@rapid-cn.com<\/a><br data-start=\"5259\" data-end=\"5262\" \/><strong data-start=\"5262\" data-end=\"5273\">Direcci\u00f3n<\/strong>:<br data-start=\"5274\" data-end=\"5277\" \/>Edificio A10, Haosi Nanpu Tech. Industrial Zone,<br data-start=\"5325\" data-end=\"5328\" \/>Calle Nanpu, calle Shajing, distrito de Bao'an,<br data-start=\"5369\" data-end=\"5372\" \/>Shenzhen, China 518104<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Terms and Conditions Our Terms and Conditions outline the rules and regulations for using our website. Please read them carefully to understand your rights and obligations while interacting with our services. Get Instant Quote IntroductionWelcome to Rapidcision. By accessing or using our website and services, you agree to comply with these Terms and Conditions. These [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-5436","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/rapidcision.com\/es\/wp-json\/wp\/v2\/pages\/5436","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rapidcision.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/rapidcision.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/rapidcision.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/rapidcision.com\/es\/wp-json\/wp\/v2\/comments?post=5436"}],"version-history":[{"count":3,"href":"https:\/\/rapidcision.com\/es\/wp-json\/wp\/v2\/pages\/5436\/revisions"}],"predecessor-version":[{"id":7178,"href":"https:\/\/rapidcision.com\/es\/wp-json\/wp\/v2\/pages\/5436\/revisions\/7178"}],"wp:attachment":[{"href":"https:\/\/rapidcision.com\/es\/wp-json\/wp\/v2\/media?parent=5436"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}